{"id":4004,"date":"2025-03-19T08:22:40","date_gmt":"2025-03-19T08:22:40","guid":{"rendered":"https:\/\/naomisalome.com\/?page_id=4004"},"modified":"2026-06-14T07:41:40","modified_gmt":"2026-06-14T07:41:40","slug":"about","status":"publish","type":"page","link":"https:\/\/naomisalome.com\/en\/about\/","title":{"rendered":"About Naomi Salom\u00e9"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"4004\" class=\"elementor elementor-4004\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-677878d elementor-section-full_width camille-columns-feature-section camille-about-page elementor-section-height-default elementor-section-height-default\" data-id=\"677878d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-eca54a7 camile-feature-image-column\" data-id=\"eca54a7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98c15ba camille-no-bottom-p camille-feature-line-detail elementor-widget elementor-widget-image\" data-id=\"98c15ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/naomisalome.com\/wp-content\/uploads\/elementor\/thumbs\/camille_line_detail-q3n6r8i17cey9g7f7izyzursafihwo7501wyctuape.png\" title=\"camille_line_detail\" alt=\"camille_line_detail\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db4d78a camille-no-bottom camille-feature-front-image elementor-widget elementor-widget-image\" data-id=\"db4d78a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/naomisalome.com\/wp-content\/uploads\/elementor\/thumbs\/Naomi-Strand-rowatwmponfl7o44m7pkmcwvtc7by9ia0jfz0zh0aa.png\" title=\"Naomi Strand\" alt=\"Naomi Strand\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f53336a camille-script-text camille-no-bottom camille-no-bottom-p elementor-widget elementor-widget-text-editor\" data-id=\"f53336a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hey, I&#8217;m Naomi!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f7c9444 camile-feature-text-column\" data-id=\"f7c9444\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fcb78de camille-no-bottom camille-no-bottom-p camille-standard-subheading elementor-widget elementor-widget-text-editor\" data-id=\"fcb78de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00dcber Naomi Salome<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0301141 camille-no-bottom camille-no-bottom-p elementor-widget elementor-widget-text-editor\" data-id=\"0301141\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6 data-start=\"131\" data-end=\"323\">Coachee. Systemische Aufstellerin. Wegbegleiterin f\u00fcr tiefgr\u00fcndige Transformation, die zur Wurzel greift.&nbsp;<\/h6>\n<h6 data-start=\"131\" data-end=\"323\">&amp;&nbsp;<\/h6>\n<h6 data-start=\"131\" data-end=\"323\">Mama. Partnerin. Marketing -Brand Managerin. Rennstrecken-Fahrerin. Bergliebhaberin.<\/h6>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a4a7770 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4a7770\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a977fa5\" data-id=\"a977fa5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4eac8f elementor-widget elementor-widget-image\" data-id=\"d4eac8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/naomisalome.com\/wp-content\/uploads\/2022\/09\/naomi-1024x683-1.jpg\" class=\"attachment-large size-large wp-image-2316\" alt=\"\" srcset=\"https:\/\/naomisalome.com\/wp-content\/uploads\/2022\/09\/naomi-1024x683-1.jpg 1024w, https:\/\/naomisalome.com\/wp-content\/uploads\/2022\/09\/naomi-1024x683-1-300x200.jpg 300w, https:\/\/naomisalome.com\/wp-content\/uploads\/2022\/09\/naomi-1024x683-1-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">In Sapa, Vietnam<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fe0820 elementor-widget elementor-widget-image\" data-id=\"2fe0820\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"753\" src=\"https:\/\/naomisalome.com\/wp-content\/uploads\/2026\/01\/IMG_20230606_005713-1024x753.jpg\" class=\"attachment-large size-large wp-image-4462\" alt=\"\" srcset=\"https:\/\/naomisalome.com\/wp-content\/uploads\/2026\/01\/IMG_20230606_005713-1024x753.jpg 1024w, https:\/\/naomisalome.com\/wp-content\/uploads\/2026\/01\/IMG_20230606_005713-300x221.jpg 300w, https:\/\/naomisalome.com\/wp-content\/uploads\/2026\/01\/IMG_20230606_005713-768x565.jpg 768w, https:\/\/naomisalome.com\/wp-content\/uploads\/2026\/01\/IMG_20230606_005713.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Mit D. Nydegger, meiner langj\u00e4hrigen Mentorin<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-080c607 elementor-widget elementor-widget-image\" data-id=\"080c607\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/naomisalome.com\/wp-content\/uploads\/2022\/09\/ducati_Klausen-56-2048x1365-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-2317\" alt=\"\" srcset=\"https:\/\/naomisalome.com\/wp-content\/uploads\/2022\/09\/ducati_Klausen-56-2048x1365-1-1024x683.jpg 1024w, https:\/\/naomisalome.com\/wp-content\/uploads\/2022\/09\/ducati_Klausen-56-2048x1365-1-300x200.jpg 300w, https:\/\/naomisalome.com\/wp-content\/uploads\/2022\/09\/ducati_Klausen-56-2048x1365-1-768x512.jpg 768w, https:\/\/naomisalome.com\/wp-content\/uploads\/2022\/09\/ducati_Klausen-56-2048x1365-1-1536x1024.jpg 1536w, https:\/\/naomisalome.com\/wp-content\/uploads\/2022\/09\/ducati_Klausen-56-2048x1365-1.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Die andere grosse  Leidenschaft<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9def72 elementor-widget elementor-widget-image\" data-id=\"d9def72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/naomisalome.com\/wp-content\/uploads\/2026\/01\/ortsstock-084.jpg\" class=\"attachment-large size-large wp-image-4465\" alt=\"\" srcset=\"https:\/\/naomisalome.com\/wp-content\/uploads\/2026\/01\/ortsstock-084.jpg 800w, https:\/\/naomisalome.com\/wp-content\/uploads\/2026\/01\/ortsstock-084-300x200.jpg 300w, https:\/\/naomisalome.com\/wp-content\/uploads\/2026\/01\/ortsstock-084-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Richtung Ortsstock, mit meinem treuen Begleiter und Lehrer, Goro<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b0cb77c\" data-id=\"b0cb77c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d54556b elementor-widget elementor-widget-text-editor\" data-id=\"d54556b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Meine Geschichte<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc4f5d3 elementor-widget elementor-widget-text-editor\" data-id=\"bc4f5d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\" data-start=\"0\" data-end=\"64\"><span style=\"letter-spacing: 0px; text-align: left;\">Mein Weg begann nicht mit einer klaren Entscheidung f\u00fcr diese Arbeit, sondern mit einem fr\u00fchen, stillen Wissen, dass es mehr gibt als das Sichtbare.<\/span><\/p><p style=\"text-align: left;\" data-start=\"380\" data-end=\"668\">Schon als Kind kam ich durch meine Mutter mit Energiearbeit in Ber\u00fchrung. F\u00fcr mich war das nichts Besonderes, sondern etwas Nat\u00fcrliches. Ich f\u00fchlte mich auch schon seit Kindheit den Tieren sehr verbunden und lerne noch vor dem Teenageralter die Tierkommunikation; zuh\u00f6ren, wahrnehmen, f\u00fchlen, sich leer machen, ganz ohne Worte. Diese feine Art des Wahrnehmens, des \u00d6ffnens hat mich fr\u00fch gepr\u00e4gt.<\/p><p style=\"text-align: left;\" data-start=\"1021\" data-end=\"1378\">Mit 16 Jahren bekam ich schwere Panikattacken.\u00a0Was folgte, war keine schnelle L\u00f6sung, sondern eine fast zehnj\u00e4hrige Reise der Heilung. Eine Zeit des Suchens, Hinterfragens, Verstehens, oft herausfordernd, manchmal einsam, aber r\u00fcckblickend zutiefst formend. Diese Jahre haben mich nicht gebrochen, sondern zu der Person gemacht, die ich heute bin.<\/p><p style=\"text-align: left;\" data-start=\"1380\" data-end=\"1878\">Parallel dazu f\u00fchrte mein \u00e4usserer Weg zun\u00e4chst in andere Richtungen.\u00a0Ich absolvierte ein Bachelorstudium als Multimedia Produzentin und arbeitete viele Jahre als Fotografin, Kreativit\u00e4t war und ist ein wichtiger Teil von mir. Doch ebenso konstant war mein inneres Forschen: Selbstheilung, k\u00f6rperliche und mentale Gesundheit, unterschiedliche Methoden, Ausbildungen und Erfahrungen. Es lief immer parallel, als roter Faden durch alles hindurch.<\/p><p style=\"text-align: left;\" data-start=\"1880\" data-end=\"2125\">Fr\u00fch habe ich verstanden, dass Gesundheit mehr ist als Symptomfreiheit.\u00a0Sie ist Freiheit. Die Freiheit, im eigenen K\u00f6rper zu wohnen. Entscheidungen bewusst zu treffen. Das eigene Leben zu gestalten. Diese Erkenntnis wurde zu einer inneren Ausrichtung.<\/p><p style=\"text-align: left;\" data-start=\"2127\" data-end=\"2425\">Auf meinem Heilungsweg spielte auch das Reisen eine grosse Rolle. Abstand, neue Perspektiven, neue Methoden und Ansatzweisen, andere Kulturen. In dieser Zeit wurde mir immer deutlicher, dass meine eigene Geschichte nicht zuf\u00e4llig war. Dass sie mich genau hierhin gef\u00fchrt hat.<\/p><p style=\"text-align: left;\" data-start=\"2427\" data-end=\"2644\">Heute verbinde ich all das:<br data-start=\"2454\" data-end=\"2457\" \/>Feines Wahrnehmen und Bodenst\u00e4ndigkeit, pers\u00f6nliche Erfahrung und fachliche Begleitung, Struktur und Intuition. Ich arbeite nicht aus einem Konzept heraus, sondern aus gelebtem Verstehen und gelerntem System.<\/p><p style=\"text-align: left;\" data-start=\"2646\" data-end=\"2791\">Meine Arbeit ist kein Versprechen auf schnelle L\u00f6sungen.<br data-start=\"2702\" data-end=\"2705\" \/>Sie ist eine Einladung, tiefer zu schauen \u2013 ehrlich, ganzheitlich und in deinem Tempo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1bba0a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1bba0a1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ba8494c\" data-id=\"ba8494c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-118c068 elementor-widget elementor-widget-spacer\" data-id=\"118c068\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1525c6f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1525c6f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f167261\" data-id=\"f167261\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a11ecd elementor-widget elementor-widget-text-editor\" data-id=\"8a11ecd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 data-start=\"277\" data-end=\"325\">Meine Arbeitsweise \u2013 dein Weg zur Ver\u00e4nderung<\/h2><p data-start=\"327\" data-end=\"648\">Im Coaching arbeiten wir in der Regel mit monatlichen Sitzungen. In diesem Rahmen nehmen wir deine aktuelle Situation in den Blick, ordnen das, was dich gerade besch\u00e4ftigt, und machen die Dynamiken sichtbar, die dich festhalten oder herausfordern. Gemeinsam entwickeln wir neue Perspektiven und konkrete n\u00e4chste Schritte.<\/p><p data-start=\"650\" data-end=\"969\">Am Ende jeder Sitzung erh\u00e4ltst du Impulse oder Aufgaben, die du \u00fcber einen Zeitraum von etwa 21 Tagen in deinen Alltag integrierst. Diese Zeit ist wichtig \u2013 nicht als Leistung, sondern als Erfahrungsraum. Sie zeigt, was in dir in Bewegung kommt, wo Widerst\u00e4nde auftauchen und was wirklich bereit ist, sich zu ver\u00e4ndern.<\/p><p data-start=\"971\" data-end=\"1282\">Echte Ver\u00e4nderung entsteht nicht durch Erkenntnis allein.\u00a0Sie entsteht dort, wo du beginnst, Verantwortung f\u00fcr dich selbst zu \u00fcbernehmen. Heilung, Wachstum und innere Freiheit lassen sich nicht delegieren \u2013 sie beginnen mit deiner Entscheidung, dir selbst Zeit, Aufmerksamkeit und Verbindlichkeit zu schenken.<\/p><p data-start=\"1284\" data-end=\"1562\">Meine Rolle ist es, dich auf diesem Weg zu begleiten.\u00a0Ich halte den Raum, stelle Fragen, gebe Impulse, Feedback und bew\u00e4hrte Methoden weiter. Ich zeige Zusammenh\u00e4nge auf und unterst\u00fctze dich dabei, deinen eigenen Rhythmus zu finden. Die Umsetzung jedoch liegt bei dir \u2013 immer.<\/p><p data-start=\"1564\" data-end=\"1749\">So entsteht kein fertiger Plan, sondern ein Prozess.\u00a0Einer, der dich Schritt f\u00fcr Schritt n\u00e4her zu dir selbst f\u00fchrt \u2013 und zu einem Leben, das sich klarer, freier und stimmiger anf\u00fchlt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dcaabb8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dcaabb8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2a063bc\" data-id=\"2a063bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-803eb5b elementor-widget elementor-widget-image\" data-id=\"803eb5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/naomisalome.com\/wp-content\/uploads\/elementor\/thumbs\/naomi-und-lua-rhm60mnh1v4nqvrgb58t1q9vrouzb6x5frquv4a90o.jpeg\" title=\"naomi und lua\" alt=\"naomi und lua\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4d641b6\" data-id=\"4d641b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-179c5b3 elementor-widget elementor-widget-image\" data-id=\"179c5b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1021\" src=\"https:\/\/naomisalome.com\/wp-content\/uploads\/2022\/03\/traveling-vietnam-1-1024x1021.jpg\" class=\"attachment-large size-large wp-image-1778\" alt=\"\" srcset=\"https:\/\/naomisalome.com\/wp-content\/uploads\/2022\/03\/traveling-vietnam-1-1024x1021.jpg 1024w, https:\/\/naomisalome.com\/wp-content\/uploads\/2022\/03\/traveling-vietnam-1-300x300.jpg 300w, https:\/\/naomisalome.com\/wp-content\/uploads\/2022\/03\/traveling-vietnam-1-150x150.jpg 150w, https:\/\/naomisalome.com\/wp-content\/uploads\/2022\/03\/traveling-vietnam-1-768x766.jpg 768w, https:\/\/naomisalome.com\/wp-content\/uploads\/2022\/03\/traveling-vietnam-1-1536x1531.jpg 1536w, https:\/\/naomisalome.com\/wp-content\/uploads\/2022\/03\/traveling-vietnam-1.jpg 1622w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3b3a3ac\" data-id=\"3b3a3ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-97838c2 elementor-widget elementor-widget-image\" data-id=\"97838c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/naomisalome.com\/wp-content\/uploads\/elementor\/thumbs\/goro-and-i-q53f65hhkbkvx645zprcccozhsjl4xenktf8694mjs.png\" title=\"goro and i\" alt=\"goro and i\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bf6a492 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bf6a492\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-777b13e\" data-id=\"777b13e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-592016c elementor-widget elementor-widget-spacer\" data-id=\"592016c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Hey, I&#8217;m Naomi! \u00dcber Naomi Salome Coachee. Systemische Aufstellerin. Wegbegleiterin f\u00fcr tiefgr\u00fcndige Transformation, die zur Wurzel greift.&nbsp; &amp;&nbsp; Mama. Partnerin. Marketing -Brand Managerin. Rennstrecken-Fahrerin. Bergliebhaberin. In Sapa, Vietnam Mit D. Nydegger, meiner langj\u00e4hrigen Mentorin Die andere grosse Leidenschaft Richtung Ortsstock, mit meinem treuen Begleiter und Lehrer, Goro Meine Geschichte Mein Weg begann nicht mit einer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-elementor.php","meta":{"footnotes":""},"class_list":["post-4004","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>About Naomi Salom\u00e9 - Naomi Salom\u00e9<\/title>\n<meta name=\"description\" content=\"Coaching &amp; Seminare f\u00fcr mentale Gesundheit, Panikattacken &amp; Marketing f\u00fcr Selbstst\u00e4ndige \u2013 individuell, praxisnah &amp; effektiv!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/naomisalome.com\/en\/about\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About Naomi Salom\u00e9 - Naomi Salom\u00e9\" \/>\n<meta property=\"og:description\" content=\"Coaching &amp; Seminare f\u00fcr mentale Gesundheit, Panikattacken &amp; Marketing f\u00fcr Selbstst\u00e4ndige \u2013 individuell, praxisnah &amp; effektiv!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/naomisalome.com\/en\/about\/\" \/>\n<meta property=\"og:site_name\" content=\"Naomi Salom\u00e9\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-14T07:41:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/naomisalome.com\/wp-content\/uploads\/elementor\/thumbs\/camille_line_detail-q3n6r8i17cey9g7f7izyzursafihwo7501wyctuape.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/naomisalome.com\\\/about\\\/\",\"url\":\"https:\\\/\\\/naomisalome.com\\\/about\\\/\",\"name\":\"About Naomi Salom\u00e9 - Naomi Salom\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/naomisalome.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/naomisalome.com\\\/about\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/naomisalome.com\\\/about\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/naomisalome.com\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/camille_line_detail-q3n6r8i17cey9g7f7izyzursafihwo7501wyctuape.png\",\"datePublished\":\"2025-03-19T08:22:40+00:00\",\"dateModified\":\"2026-06-14T07:41:40+00:00\",\"description\":\"Coaching & Seminare f\u00fcr mentale Gesundheit, Panikattacken & Marketing f\u00fcr Selbstst\u00e4ndige \u2013 individuell, praxisnah & effektiv!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/naomisalome.com\\\/about\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/naomisalome.com\\\/about\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/naomisalome.com\\\/about\\\/#primaryimage\",\"url\":\"https:\\\/\\\/naomisalome.com\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/camille_line_detail-q3n6r8i17cey9g7f7izyzursafihwo7501wyctuape.png\",\"contentUrl\":\"https:\\\/\\\/naomisalome.com\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/camille_line_detail-q3n6r8i17cey9g7f7izyzursafihwo7501wyctuape.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/naomisalome.com\\\/about\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/naomisalome.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About Naomi Salom\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/naomisalome.com\\\/#website\",\"url\":\"https:\\\/\\\/naomisalome.com\\\/\",\"name\":\"Naomi Salom\u00e9\",\"description\":\"Ganzheitlich Begleitet\",\"publisher\":{\"@id\":\"https:\\\/\\\/naomisalome.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/naomisalome.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/naomisalome.com\\\/#organization\",\"name\":\"Naomi Salom\u00e9\",\"url\":\"https:\\\/\\\/naomisalome.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/naomisalome.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/naomisalome.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/cropped-Naomi-Salome.png\",\"contentUrl\":\"https:\\\/\\\/naomisalome.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/cropped-Naomi-Salome.png\",\"width\":1158,\"height\":599,\"caption\":\"Naomi Salom\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/naomisalome.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"About Naomi Salom\u00e9 - Naomi Salom\u00e9","description":"Coaching & Seminare f\u00fcr mentale Gesundheit, Panikattacken & Marketing f\u00fcr Selbstst\u00e4ndige \u2013 individuell, praxisnah & effektiv!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/naomisalome.com\/en\/about\/","og_locale":"en_GB","og_type":"article","og_title":"About Naomi Salom\u00e9 - Naomi Salom\u00e9","og_description":"Coaching & Seminare f\u00fcr mentale Gesundheit, Panikattacken & Marketing f\u00fcr Selbstst\u00e4ndige \u2013 individuell, praxisnah & effektiv!","og_url":"https:\/\/naomisalome.com\/en\/about\/","og_site_name":"Naomi Salom\u00e9","article_modified_time":"2026-06-14T07:41:40+00:00","og_image":[{"url":"https:\/\/naomisalome.com\/wp-content\/uploads\/elementor\/thumbs\/camille_line_detail-q3n6r8i17cey9g7f7izyzursafihwo7501wyctuape.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/naomisalome.com\/about\/","url":"https:\/\/naomisalome.com\/about\/","name":"About Naomi Salom\u00e9 - Naomi Salom\u00e9","isPartOf":{"@id":"https:\/\/naomisalome.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/naomisalome.com\/about\/#primaryimage"},"image":{"@id":"https:\/\/naomisalome.com\/about\/#primaryimage"},"thumbnailUrl":"https:\/\/naomisalome.com\/wp-content\/uploads\/elementor\/thumbs\/camille_line_detail-q3n6r8i17cey9g7f7izyzursafihwo7501wyctuape.png","datePublished":"2025-03-19T08:22:40+00:00","dateModified":"2026-06-14T07:41:40+00:00","description":"Coaching & Seminare f\u00fcr mentale Gesundheit, Panikattacken & Marketing f\u00fcr Selbstst\u00e4ndige \u2013 individuell, praxisnah & effektiv!","breadcrumb":{"@id":"https:\/\/naomisalome.com\/about\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/naomisalome.com\/about\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/naomisalome.com\/about\/#primaryimage","url":"https:\/\/naomisalome.com\/wp-content\/uploads\/elementor\/thumbs\/camille_line_detail-q3n6r8i17cey9g7f7izyzursafihwo7501wyctuape.png","contentUrl":"https:\/\/naomisalome.com\/wp-content\/uploads\/elementor\/thumbs\/camille_line_detail-q3n6r8i17cey9g7f7izyzursafihwo7501wyctuape.png"},{"@type":"BreadcrumbList","@id":"https:\/\/naomisalome.com\/about\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/naomisalome.com\/"},{"@type":"ListItem","position":2,"name":"About Naomi Salom\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/naomisalome.com\/#website","url":"https:\/\/naomisalome.com\/","name":"Naomi Salom\u00e9","description":"Ganzheitlich Begleitet","publisher":{"@id":"https:\/\/naomisalome.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/naomisalome.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/naomisalome.com\/#organization","name":"Naomi Salom\u00e9","url":"https:\/\/naomisalome.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/naomisalome.com\/#\/schema\/logo\/image\/","url":"https:\/\/naomisalome.com\/wp-content\/uploads\/2026\/06\/cropped-Naomi-Salome.png","contentUrl":"https:\/\/naomisalome.com\/wp-content\/uploads\/2026\/06\/cropped-Naomi-Salome.png","width":1158,"height":599,"caption":"Naomi Salom\u00e9"},"image":{"@id":"https:\/\/naomisalome.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/naomisalome.com\/en\/wp-json\/wp\/v2\/pages\/4004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/naomisalome.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/naomisalome.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/naomisalome.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/naomisalome.com\/en\/wp-json\/wp\/v2\/comments?post=4004"}],"version-history":[{"count":28,"href":"https:\/\/naomisalome.com\/en\/wp-json\/wp\/v2\/pages\/4004\/revisions"}],"predecessor-version":[{"id":4806,"href":"https:\/\/naomisalome.com\/en\/wp-json\/wp\/v2\/pages\/4004\/revisions\/4806"}],"wp:attachment":[{"href":"https:\/\/naomisalome.com\/en\/wp-json\/wp\/v2\/media?parent=4004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}